{"id":6491,"date":"2026-07-15T11:59:00","date_gmt":"2026-07-15T14:59:00","guid":{"rendered":"https:\/\/www.apedu.org.br\/site\/?p=6491"},"modified":"2026-07-15T12:00:20","modified_gmt":"2026-07-15T15:00:20","slug":"academica-nina-ranieri-conduz-curadoria-de-edicao-que-consolida-o-premio-jabuti-academico","status":"publish","type":"post","link":"https:\/\/www.apedu.org.br\/site\/academica-nina-ranieri-conduz-curadoria-de-edicao-que-consolida-o-premio-jabuti-academico\/","title":{"rendered":"Acad\u00eamica Nina Ranieri conduz curadoria de edi\u00e7\u00e3o que consolida o Pr\u00eamio Jabuti Acad\u00eamico"},"content":{"rendered":"\n<p><em>Divulga\u00e7\u00e3o dos semifinalistas re\u00fane alguns dos principais intelectuais, pesquisadores e editoras universit\u00e1rias do pa\u00eds e reafirma o papel do pr\u00eamio como refer\u00eancia na valoriza\u00e7\u00e3o da produ\u00e7\u00e3o cient\u00edfica brasileira.<\/em><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"348\" height=\"245\" src=\"https:\/\/www.apedu.org.br\/site\/wp-content\/uploads\/2026\/05\/image-6.png\" alt=\"\" class=\"wp-image-6358\" srcset=\"https:\/\/www.apedu.org.br\/site\/wp-content\/uploads\/2026\/05\/image-6.png 348w, https:\/\/www.apedu.org.br\/site\/wp-content\/uploads\/2026\/05\/image-6-300x211.png 300w\" sizes=\"auto, (max-width: 348px) 100vw, 348px\" \/><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<p>A divulga\u00e7\u00e3o dos semifinalistas da terceira edi\u00e7\u00e3o do Pr\u00eamio Jabuti Acad\u00eamico, realizada pela C\u00e2mara Brasileira do Livro (CBL), confirmou a consolida\u00e7\u00e3o da premia\u00e7\u00e3o como o mais importante reconhecimento \u00e0s obras acad\u00eamicas, cient\u00edficas, t\u00e9cnicas e profissionais publicadas no Brasil. \u00c0 frente da curadoria da edi\u00e7\u00e3o de 2026 est\u00e1 a acad\u00eamica da Academia Paulista de Educa\u00e7\u00e3o Nina Ranieri, respons\u00e1vel pela coordena\u00e7\u00e3o t\u00e9cnica do pr\u00eamio desde sua cria\u00e7\u00e3o.<\/p>\n\n\n\n<p>A lista re\u00fane autores de reconhecida proje\u00e7\u00e3o nacional, entre eles Eug\u00eanio Bucci, semifinalista na categoria Comunica\u00e7\u00e3o e Informa\u00e7\u00e3o com <em>A Raz\u00e3o Desumana: Cultura e Informa\u00e7\u00e3o na Era da Desinforma\u00e7\u00e3o Inculta<\/em> (Aut\u00eantica); Marilena Chaui, indicada em Filosofia com <em>Por Que Filosofia?<\/em> (GEN\/LTC); Vera Iaconelli, em Psicologia e Psican\u00e1lise com <em>An\u00e1lise<\/em> (Zahar); e Daniel Martins de Barros, com <em>Sofrimento N\u00e3o \u00c9 Doen\u00e7a<\/em> (Sextante).<\/p>\n\n\n\n<p>A diversidade tem\u00e1tica tamb\u00e9m se reflete na presen\u00e7a de importantes editoras brasileiras, como Edusp, Aut\u00eantica, Blucher, Companhia das Letras, Record, PUC-Rio, Contexto, Loyola, Zahar, Sextante, Nyota, Jaguatirica e diversas editoras universit\u00e1rias, evidenciando a vitalidade da produ\u00e7\u00e3o editorial voltada \u00e0 pesquisa e \u00e0 difus\u00e3o do conhecimento.<\/p>\n\n\n\n<p>Outro destaque da edi\u00e7\u00e3o \u00e9 o an\u00fancio do Livro Acad\u00eamico Cl\u00e1ssico de 2026, distin\u00e7\u00e3o concedida \u00e0 obra <em>Hist\u00f3ria das Mulheres no Brasil<\/em>, organizada pela historiadora Mary Del Priore. A escolha reconhece um livro que ampliou o entendimento sobre a forma\u00e7\u00e3o da sociedade brasileira e permanece como refer\u00eancia indispens\u00e1vel para pesquisadores, professores e estudantes. Em entrevista ao jornal <em>O Estado de S. Paulo<\/em>, Nina Ranieri observou que se trata de &#8220;um cl\u00e1ssico que continua oferecendo novas possibilidades de leitura, reflex\u00e3o e produ\u00e7\u00e3o de conhecimento&#8221;.<\/p>\n\n\n\n<p>Para o presidente da Academia Paulista de Educa\u00e7\u00e3o, Hubert Alqu\u00e9res, &#8220;a presen\u00e7a de Nina Ranieri na coordena\u00e7\u00e3o de uma premia\u00e7\u00e3o dessa dimens\u00e3o reafirma sua destacada contribui\u00e7\u00e3o para a vida acad\u00eamica brasileira e para o fortalecimento da produ\u00e7\u00e3o cient\u00edfica nacional&#8221;. Ainda segundo o professor, &#8220;sob a lideran\u00e7a de Nina, o Jabuti Acad\u00eamico consolidou crit\u00e9rios rigorosos de avalia\u00e7\u00e3o, ampliou o reconhecimento da literatura cient\u00edfica e ocupa, cada vez mais, posi\u00e7\u00e3o de destaque entre as principais premia\u00e7\u00f5es do conhecimento no pa\u00eds&#8221;.<\/p>\n\n\n\n<p>Os finalistas de cada categoria ser\u00e3o anunciados em 27 de julho, e os vencedores ser\u00e3o conhecidos em cerim\u00f4nia marcada para 11 de agosto, no Teatro S\u00e9rgio Cardoso, em S\u00e3o Paulo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Divulga\u00e7\u00e3o dos semifinalistas re\u00fane alguns dos principais intelectuais, pesquisadores e editoras universit\u00e1rias do pa\u00eds e reafirma o papel do pr\u00eamio como refer\u00eancia na valoriza\u00e7\u00e3o da produ\u00e7\u00e3o cient\u00edfica brasileira. A divulga\u00e7\u00e3o dos semifinalistas da terceira edi\u00e7\u00e3o do Pr\u00eamio Jabuti Acad\u00eamico, realizada pela C\u00e2mara Brasileira do Livro (CBL), confirmou a consolida\u00e7\u00e3o da premia\u00e7\u00e3o como o mais importante reconhecimento \u00e0s obras acad\u00eamicas, cient\u00edficas, t\u00e9cnicas e profissionais publicadas no Brasil. \u00c0 frente da curadoria da edi\u00e7\u00e3o de 2026 est\u00e1 a acad\u00eamica da Academia Paulista de Educa\u00e7\u00e3o Nina Ranieri, respons\u00e1vel pela coordena\u00e7\u00e3o t\u00e9cnica do pr\u00eamio desde sua cria\u00e7\u00e3o. A lista re\u00fane autores de reconhecida proje\u00e7\u00e3o [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":6358,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[],"class_list":["post-6491","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/www.apedu.org.br\/site\/wp-json\/wp\/v2\/posts\/6491","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.apedu.org.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.apedu.org.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.apedu.org.br\/site\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.apedu.org.br\/site\/wp-json\/wp\/v2\/comments?post=6491"}],"version-history":[{"count":1,"href":"https:\/\/www.apedu.org.br\/site\/wp-json\/wp\/v2\/posts\/6491\/revisions"}],"predecessor-version":[{"id":6492,"href":"https:\/\/www.apedu.org.br\/site\/wp-json\/wp\/v2\/posts\/6491\/revisions\/6492"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.apedu.org.br\/site\/wp-json\/wp\/v2\/media\/6358"}],"wp:attachment":[{"href":"https:\/\/www.apedu.org.br\/site\/wp-json\/wp\/v2\/media?parent=6491"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.apedu.org.br\/site\/wp-json\/wp\/v2\/categories?post=6491"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.apedu.org.br\/site\/wp-json\/wp\/v2\/tags?post=6491"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}