{"id":6494,"date":"2026-06-24T11:50:17","date_gmt":"2026-06-24T14:50:17","guid":{"rendered":"https:\/\/www.apedu.org.br\/site\/?p=6494"},"modified":"2026-07-15T11:55:00","modified_gmt":"2026-07-15T14:55:00","slug":"artigo-o-poder-irresistivel-do-entusiasmo","status":"publish","type":"post","link":"https:\/\/www.apedu.org.br\/site\/artigo-o-poder-irresistivel-do-entusiasmo\/","title":{"rendered":"Artigo &#8211; O poder irresist\u00edvel do entusiasmo"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"613\" height=\"348\" src=\"https:\/\/www.apedu.org.br\/site\/wp-content\/uploads\/2026\/06\/image-5.png\" alt=\"\" class=\"wp-image-6433\" srcset=\"https:\/\/www.apedu.org.br\/site\/wp-content\/uploads\/2026\/06\/image-5.png 613w, https:\/\/www.apedu.org.br\/site\/wp-content\/uploads\/2026\/06\/image-5-300x170.png 300w, https:\/\/www.apedu.org.br\/site\/wp-content\/uploads\/2026\/06\/image-5-400x227.png 400w\" sizes=\"auto, (max-width: 613px) 100vw, 613px\" \/><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<p><em>Grandes momentos da hist\u00f3ria foram protagonizados por pessoas que recorreram ao entusiasmo para superar limita\u00e7\u00f5es<\/em><a href=\"https:\/\/www.cbnsantos.com.br\/autor\/reinaldo-polito\/\"><\/a><\/p>\n\n\n\n<p>Por Reinaldo Polito<\/p>\n\n\n\n<p>H\u00e1 uma hist\u00f3ria que vale a pena conhecer. Ela foi contada no livro Do fracasso ao sucesso nas vendas, de Frank Bettger. Depois de fracassar em diversas atividades e querendo mudar de vida, ele decidiutrabalhar como corretor em uma seguradora. Sua expectativa era conseguir uma boa remunera\u00e7\u00e3o.<\/p>\n\n\n\n<p>O resultado, entretanto, ficou muito distante do que imaginava. Passados alguns meses, n\u00e3o havia realizado nenhum neg\u00f3cio. Como tinha frequentado apenas o curso m\u00e9dio, a dificuldade para encontrar outro trabalho era grande. N\u00e3o poderia continuar ali. Precisava sobreviver. A \u00fanica possibilidade parecia ser voltar ao que fazia no passado: trabalhar como cobrador usando a bicicleta.<\/p>\n\n\n\n<p><strong>Uma reviravolta<\/strong><a href=\"https:\/\/www.cbnsantos.com.br\/noticias\/noticias\/senado-aprova-mp-do-frete-sob-pressao-de-greve-e-texto-segue-para-sancao-de-lula.html\"><\/a><\/p>\n\n\n\n<p>O destino, por\u00e9m, tinha outros planos. Bettger precisou retornar \u00e0 corretora para pegar alguns pertences deixados na gaveta. Por acaso, naquele dia o presidente da empresa ministrava um curso para os vendedores. Bettger o admirava profundamente. Afinal, ele come\u00e7ara na corretora aos 11 anos de idade e alcan\u00e7ara o mais alto posto hier\u00e1rquico da companhia.<\/p>\n\n\n\n<p>Resolveu ouvir o que aquele grande comandante tinha a ensinar. Recebeu orienta\u00e7\u00f5es para fazer determinado n\u00famero de visitas di\u00e1rias e organizar os dias da semana para saber quem deveria procurar. Colocou em pr\u00e1tica aquelas recomenda\u00e7\u00f5es e deu certo. As vendas come\u00e7aram a acontecer.<\/p>\n\n\n\n<p><strong>Do fracasso ao sucesso<\/strong><\/p>\n\n\n\n<p>Uma das li\u00e7\u00f5es mais importantes que recebeu foi a de que nenhuma t\u00e9cnica de vendas supera o entusiasmo. Aprendeu que o \u00e2nimo de um profissional pode at\u00e9 compensar defici\u00eancias t\u00e9cnicas. Essa disposi\u00e7\u00e3o transformou sua vida. Bettger se tornaria um dos vendedores mais bem-sucedidos dos Estados Unidos.<\/p>\n\n\n\n<p>Grandes momentos da hist\u00f3ria foram protagonizados por pessoas que recorreram ao entusiasmo para superar limita\u00e7\u00f5es. Na orat\u00f3ria, h\u00e1 exemplos extraordin\u00e1rios de oradores que fracassaram nas primeiras vezes em que ocuparam a tribuna. \u00c9 o caso de Dem\u00f3stenes, considerado o maior orador da Antiguidade.<\/p>\n\n\n\n<p><strong>A dedica\u00e7\u00e3o de Dem\u00f3stenes<\/strong><\/p>\n\n\n\n<p>Possu\u00eda voz fraca. Sua dic\u00e7\u00e3o era sofr\u00edvel. Tinha o h\u00e1bito de levantar constantemente o ombro enquanto falava. Era ridicularizado por causa dessas defici\u00eancias. Ainda assim, decidiu que se transformaria em um grande orador.<\/p>\n\n\n\n<p>Raspou metade do cabelo e da barba para n\u00e3o cair na tenta\u00e7\u00e3o de abandonar o isolamento a que se submetera. Para fortalecer a voz, fazia caminhadas di\u00e1rias na praia. Corrigiu a dic\u00e7\u00e3o treinando com seixos na boca. Colocou uma espada apontada para o ombro e, toda vez que fazia o movimento inadequado, acabava ferido. Foi assim, movido por determina\u00e7\u00e3o quase obsessiva, que se transformou em um dos maiores exemplos da orat\u00f3ria.<\/p>\n\n\n\n<p><strong>A defesa do filho<\/strong><\/p>\n\n\n\n<p>Outro homem que deu demonstra\u00e7\u00f5es impressionantes do poder do entusiasmo foi Victor Hugo, autor de Os Miser\u00e1veis. Ele ofereceu um exemplo admir\u00e1vel de como uma causa pode ser defendida quando acreditamos profundamente nela.<\/p>\n\n\n\n<p>Seu filho, Charles Hugo, depois de presenciar a luta desesperada de um condenado \u00e0 morte para tentar salvar a pr\u00f3pria vida, ficou t\u00e3o indignado com a situa\u00e7\u00e3o que escreveu um artigo contra a pena capital e o publicou em um dos mais importantes jornais franceses da \u00e9poca. Como a pena de morte era prevista em lei, advers\u00e1rios da fam\u00edlia aproveitaram o epis\u00f3dio para atacar o grande escritor processando o jovem.<\/p>\n\n\n\n<p><strong>A emo\u00e7\u00e3o compensou a falta da t\u00e9cnica<\/strong><\/p>\n\n\n\n<p>Levado a julgamento, o pr\u00f3prio Victor Hugo decidiu assumir a defesa do filho. Proferiu um discurso t\u00e3o emocionado que, mesmo sem ser advogado e sem dominar a t\u00e9cnica jur\u00eddica, conseguiu absolver o ente querido:<\/p>\n\n\n\n<p>&#8220;O verdadeiro culpado neste assunto, se h\u00e1 algum, n\u00e3o \u00e9 meu filho; sou eu!\u201d<\/p>\n\n\n\n<p>Com voz forte e tomada pela emo\u00e7\u00e3o, Victor Hugo se agiganta diante do tribunal e repete:<\/p>\n\n\n\n<p>\u201cSou eu!\u201d<\/p>\n\n\n\n<p>E, como se defendesse a pr\u00f3pria vida, acrescenta:<\/p>\n\n\n\n<p>\u201cEsse crime \u2014 o de combater a pena de morte \u2014 cometi-o muito antes que meu filho. E me denuncio, senhores! Cometi-o com todas as circunst\u00e2ncias agravantes: com premedita\u00e7\u00e3o, com tenacidade, com reincid\u00eancia!\u201d<\/p>\n\n\n\n<p><strong>Nem um grande advogado faria melhor<\/strong><\/p>\n\n\n\n<p>Entregando-se de corpo e alma \u00e0 defesa do filho, chama para si toda a responsabilidade daquela atitude:<\/p>\n\n\n\n<p>\u201cIsso que meu filho escreveu, s\u00f3 o escreveu porque eu o inspirei desde a inf\u00e2ncia; porque, ao mesmo tempo em que \u00e9 meu filho segundo o sangue, \u00e9 meu filho segundo o esp\u00edrito; porque quer continuar a tradi\u00e7\u00e3o de seu pai. Eis a\u00ed um delito estranho, e pelo qual me admiro que se queira persegui-lo!\u201d<\/p>\n\n\n\n<p>Ser\u00e1 que algum advogado, por mais profundo que fosse seu conhecimento da legisla\u00e7\u00e3o francesa, conseguiria pronunciar palavras t\u00e3o emocionadas e capazes de revelar de forma t\u00e3o intensa o sentimento daquele pai?<\/p>\n\n\n\n<p>A emo\u00e7\u00e3o verdadeira \u00e9 contagiante. Envolve os liderados, desperta energia e os transforma em uma extens\u00e3o revigorada da nossa vontade.<\/p>\n\n\n\n<p>______________________________________ <\/p>\n\n\n\n<p>Reinaldo Polito \u00e9 Presidente Em\u00e9rito da Academia Paulista de Educa\u00e7\u00e3o, Mestre em Ci\u00eancias da Comunica\u00e7\u00e3o e professor de orat\u00f3ria nos cursos de p\u00f3s-gradua\u00e7\u00e3o em Marketing Pol\u00edtico, Gest\u00e3o Corporativa e Gest\u00e3o de Comunica\u00e7\u00e3o e Marketing na ECA-USP. Escreveu 34 livros com mais de 1,5 milh\u00e3o de exemplares vendidos em 39 pa\u00edses. Siga pelo Instagram: @polito<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Grandes momentos da hist\u00f3ria foram protagonizados por pessoas que recorreram ao entusiasmo para superar limita\u00e7\u00f5es Por Reinaldo Polito H\u00e1 uma hist\u00f3ria que vale a pena conhecer. Ela foi contada no livro Do fracasso ao sucesso nas vendas, de Frank Bettger. Depois de fracassar em diversas atividades e querendo mudar de vida, ele decidiutrabalhar como corretor em uma seguradora. Sua expectativa era conseguir uma boa remunera\u00e7\u00e3o. O resultado, entretanto, ficou muito distante do que imaginava. Passados alguns meses, n\u00e3o havia realizado nenhum neg\u00f3cio. Como tinha frequentado apenas o curso m\u00e9dio, a dificuldade para encontrar outro trabalho era grande. N\u00e3o poderia continuar [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":6433,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,11],"tags":[],"class_list":["post-6494","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-artigos","category-noticias"],"_links":{"self":[{"href":"https:\/\/www.apedu.org.br\/site\/wp-json\/wp\/v2\/posts\/6494","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.apedu.org.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.apedu.org.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.apedu.org.br\/site\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.apedu.org.br\/site\/wp-json\/wp\/v2\/comments?post=6494"}],"version-history":[{"count":2,"href":"https:\/\/www.apedu.org.br\/site\/wp-json\/wp\/v2\/posts\/6494\/revisions"}],"predecessor-version":[{"id":6497,"href":"https:\/\/www.apedu.org.br\/site\/wp-json\/wp\/v2\/posts\/6494\/revisions\/6497"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.apedu.org.br\/site\/wp-json\/wp\/v2\/media\/6433"}],"wp:attachment":[{"href":"https:\/\/www.apedu.org.br\/site\/wp-json\/wp\/v2\/media?parent=6494"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.apedu.org.br\/site\/wp-json\/wp\/v2\/categories?post=6494"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.apedu.org.br\/site\/wp-json\/wp\/v2\/tags?post=6494"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}